{"id":238906,"date":"2023-02-07T09:27:02","date_gmt":"2023-02-07T08:27:02","guid":{"rendered":"https:\/\/eko-haus.de\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/"},"modified":"2023-06-01T14:56:32","modified_gmt":"2023-06-01T12:56:32","slug":"%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a","status":"publish","type":"page","link":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/","title":{"rendered":"\u5730\u6b4c\u4e09\u5473\u7dda"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;15px|15px|15px|15px|true|true&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; header_3_text_color=&#8221;gcid-1021896a-c9ac-4359-99df-3f865b79985b&#8221; header_4_text_color=&#8221;gcid-1021896a-c9ac-4359-99df-3f865b79985b&#8221; global_colors_info=&#8221;{%22gcid-1021896a-c9ac-4359-99df-3f865b79985b%22:%91%22header_4_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<div class=\"em em-view-container\" id=\"em-view-1945906424\" data-view=\"list\">\r\n\t<div class=\"em pixelbones em-list em-events-list\" id=\"em-events-list-1945906424\" data-view-id=\"1945906424\">\r\n\t\u73fe\u5728\u3001\u3053\u306e\u30ab\u30c6\u30b4\u30ea\u306e\u30a4\u30d9\u30f3\u30c8\u306f\u3042\u308a\u307e\u305b\u3093\u3002 \u3059\u3050\u306b\u623b\u3063\u3066\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002\t<\/div>\r\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"em em-view-container\" id=\"em-view-1742196559\" data-view=\"list\">\r\n\t<div class=\"em pixelbones em-list em-events-list\" id=\"em-events-list-1742196559\" data-view-id=\"1742196559\">\r\n\t\u73fe\u5728\u3001\u3053\u306e\u30ab\u30c6\u30b4\u30ea\u306e\u30a4\u30d9\u30f3\u30c8\u306f\u3042\u308a\u307e\u305b\u3093\u3002 \u3059\u3050\u306b\u623b\u3063\u3066\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002\t<\/div>\r\n<\/div>\n","protected":false},"author":2,"featured_media":239318,"parent":238879,"menu_order":27,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-238906","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EK\u014c-Haus &#8226; \u5730\u6b4c\u4e09\u5473\u7dda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EK\u014c-Haus &#8226; \u5730\u6b4c\u4e09\u5473\u7dda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/\" \/>\n<meta property=\"og:site_name\" content=\"EK\u014c-Haus\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T12:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eko-haus.de\/wp-content\/uploads\/2023\/02\/Jiuta-Shamisen-Workshop-e1684595750250.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"472\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/\",\"url\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/\",\"name\":\"EK\u014c-Haus &#8226; \u5730\u6b4c\u4e09\u5473\u7dda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eko-haus.de\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Jiuta-Shamisen-Workshop-e1684595750250.jpg\",\"datePublished\":\"2023-02-07T08:27:02+00:00\",\"dateModified\":\"2023-06-01T12:56:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eko-haus.de\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Jiuta-Shamisen-Workshop-e1684595750250.jpg\",\"contentUrl\":\"https:\\\/\\\/eko-haus.de\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Jiuta-Shamisen-Workshop-e1684595750250.jpg\",\"width\":472,\"height\":314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u50ac\u4e8b\",\"item\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u30b3\u30fc\u30b9\u3068\u30ef\u30fc\u30af\u30b7\u30e7\u30c3\u30d7\",\"item\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\\\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u5730\u6b4c\u4e09\u5473\u7dda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/\",\"name\":\"EK\u014c-Haus\",\"description\":\"der JapanischenKulturen e.V.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eko-haus.de\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EK\u014c-Haus &#8226; \u5730\u6b4c\u4e09\u5473\u7dda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/","og_locale":"ja_JP","og_type":"article","og_title":"EK\u014c-Haus &#8226; \u5730\u6b4c\u4e09\u5473\u7dda","og_url":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/","og_site_name":"EK\u014c-Haus","article_modified_time":"2023-06-01T12:56:32+00:00","og_image":[{"width":472,"height":314,"url":"https:\/\/eko-haus.de\/wp-content\/uploads\/2023\/02\/Jiuta-Shamisen-Workshop-e1684595750250.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/","url":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/","name":"EK\u014c-Haus &#8226; \u5730\u6b4c\u4e09\u5473\u7dda","isPartOf":{"@id":"https:\/\/eko-haus.de\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/#primaryimage"},"image":{"@id":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/#primaryimage"},"thumbnailUrl":"https:\/\/eko-haus.de\/wp-content\/uploads\/2023\/02\/Jiuta-Shamisen-Workshop-e1684595750250.jpg","datePublished":"2023-02-07T08:27:02+00:00","dateModified":"2023-06-01T12:56:32+00:00","breadcrumb":{"@id":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/#primaryimage","url":"https:\/\/eko-haus.de\/wp-content\/uploads\/2023\/02\/Jiuta-Shamisen-Workshop-e1684595750250.jpg","contentUrl":"https:\/\/eko-haus.de\/wp-content\/uploads\/2023\/02\/Jiuta-Shamisen-Workshop-e1684595750250.jpg","width":472,"height":314},{"@type":"BreadcrumbList","@id":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/%e5%9c%b0%e6%ad%8c%e4%b8%89%e5%91%b3%e7%b7%9a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/eko-haus.de\/ja\/"},{"@type":"ListItem","position":2,"name":"\u50ac\u4e8b","item":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/"},{"@type":"ListItem","position":3,"name":"\u30b3\u30fc\u30b9\u3068\u30ef\u30fc\u30af\u30b7\u30e7\u30c3\u30d7","item":"https:\/\/eko-haus.de\/ja\/%e5%82%ac%e4%ba%8b%e3%83%97%e3%83%ad%e3%82%b0%e3%83%a9%e3%83%a0\/%e3%82%b3%e3%83%bc%e3%82%b9%e3%81%a8%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97\/"},{"@type":"ListItem","position":4,"name":"\u5730\u6b4c\u4e09\u5473\u7dda"}]},{"@type":"WebSite","@id":"https:\/\/eko-haus.de\/ja\/#website","url":"https:\/\/eko-haus.de\/ja\/","name":"EK\u014c-Haus","description":"der JapanischenKulturen e.V.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eko-haus.de\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/pages\/238906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/comments?post=238906"}],"version-history":[{"count":12,"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/pages\/238906\/revisions"}],"predecessor-version":[{"id":239321,"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/pages\/238906\/revisions\/239321"}],"up":[{"embeddable":true,"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/pages\/238879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/media\/239318"}],"wp:attachment":[{"href":"https:\/\/eko-haus.de\/ja\/wp-json\/wp\/v2\/media?parent=238906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}